{"id":1305,"date":"2023-10-10T09:06:00","date_gmt":"2023-10-10T09:06:00","guid":{"rendered":"https:\/\/metrecubic.com\/?p=1305"},"modified":"2024-08-01T11:34:21","modified_gmt":"2024-08-01T11:34:21","slug":"la-triatlon-de-sgrail-100","status":"publish","type":"post","link":"https:\/\/metrecubic.com\/es\/blog\/la-triatlon-de-sgrail-100\/","title":{"rendered":"La Triatl\u00f3n de SGRAIL 100"},"content":{"rendered":"\n<p>Este fin de semana, <a href=\"https:\/\/metrecubic.com\">Metrecubic<\/a> ha participado en <a href=\"https:\/\/sgrail100.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">la Triatl\u00f3n de SGRAIL 100<\/a>, una gran competici\u00f3n a nivel internacional. La competici\u00f3n ten\u00eda como origen Cadaqu\u00e9s y su destino era en Girona, transportando as\u00ed, m\u00e1s de 300 bicicletas con nuestros camiones.<\/p>\n\n\n\n<p>Los participantes eran todos de diferentes nacionalidades ya que ven\u00edan de toda Europa.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00bfConoc\u00edas la Triatl\u00f3n de SGRAIL 100?<\/h2>\n\n\n\n<p>Si no conoc\u00edas la Triatl\u00f3n de SGRAIL 100, tienes que saber que se trata de un evento deportivo que consta de tres etapas:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>1\u20195km nadando<\/li>\n\n\n\n<li>88km de Gravel<\/li>\n\n\n\n<li>10\u20195km de Trail.<\/li>\n<\/ul>\n\n\n\n<p>Durante el evento, los participantes tienen que transportar las bicicletas desde Girona hasta Cadaqu\u00e9s de una forma segura, por eso desde <a href=\"https:\/\/www.klassmark.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">Klassmark<\/a>, todos los a\u00f1os nos llaman para transportar, con la mayor seguridad, las m\u00e1s de 300 bicicletas de sus competidores.<\/p>\n\n\n\n<p>Tambi\u00e9n es posible que cada participante transporte su bicicleta por su propio medio, pero no es lo m\u00e1s recomendable, debido a la gran afluencia de gente en Cadaqu\u00e9s y al poco sitio para poder aparcar.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Se inicia la Triatl\u00f3n SGRAIL 100<\/h3>\n\n\n\n<p>Una vez empieza el evento viene la primera etapa y, despu\u00e9s de 1\u20195km nadando, tienes que coger la bicicleta para hacer 88km. Por esta raz\u00f3n, el veh\u00edculo se queda en Cadaqu\u00e9s, que en caso de ir acompa\u00f1ado no habr\u00eda problema, pero si no es el caso, all\u00ed se quedar\u00eda tu bici para ir otro d\u00eda a recogerlo, y eso no es muy conveniente.<\/p>\n\n\n\n<p>Tambi\u00e9n es cierto, que Klassmark ya incluye el transporte de la bici dentro del precio de inscripci\u00f3n, as\u00ed que no aprovecharlo tambi\u00e9n ser\u00eda una tonter\u00eda.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u00bfSabes c\u00f3mo se transportan?<\/h3>\n\n\n\n<p>En primer lugar, se estructuran las bicicletas por n\u00fameros de dorsal y as\u00ed se pueden clasificar en orden y tener control de los n\u00fameros de dorsal. As\u00ed pues, se pueden descargar en el mismo orden y se pueden poner en su lugar exacto.<\/p>\n\n\n\n<p>Debido a que son bicicletas delicadas, deben ser transportadas con material flexible, pero no tiene que ser duro, ya que debemos tener la posibilidad de entrelazarlas para tener una mayor capacidad dentro de la furgoneta, o cami\u00f3n, para que quepan el m\u00e1ximo de bicicletas posibles. Es por ello, que entre una y otra, se protegen con cart\u00f3n y mantas para que no se toquen entre ellas. En consecuencia, hace que no se da\u00f1en y lleguen en perfectas condiciones a su destino.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u00bfQu\u00e9 capacidad cabe en cada veh\u00edculo?<\/h3>\n\n\n\n<p>La capacidad depende un poco del veh\u00edculo en s\u00ed que se utilice, pero para tener una orientaci\u00f3n, estar\u00edamos hablando que una furgoneta de 14m3 puede llegar a abarcar unas 27 bicis y un cami\u00f3n de 40m3 unas 90.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Con Metrecubic puedes organizar diferentes tipos transportes<\/h2>\n\n\n\n<p>Puedes contar con Metrecubic, tanto a nivel Nacional y\/o Internacional, como tambi\u00e9n puedes pedirlo a nivel particular, de empresa, o incluso para un evento deportivo como es la Triatl\u00f3n de SGRAIL 100.<\/p>\n\n\n\n<p>Si tienes cualquier duda o quieres pedir m\u00e1s informaci\u00f3n, no dudes en <a href=\"https:\/\/metrecubic.com\/contacto\/\">contactarnos<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este fin de semana, Metrecubic ha participado en la Triatl\u00f3n de SGRAIL 100, una gran competici\u00f3n a nivel internacional. La competici\u00f3n ten\u00eda como origen Cadaqu\u00e9s y su destino era en &hellip;<\/p>\n","protected":false},"author":1,"featured_media":4231,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[124],"tags":[],"class_list":["post-1305","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-metrecubic"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Triatl\u00f3n de SGRAIL 100 - METRECUBIC<\/title>\n<meta name=\"description\" content=\"Este fin de semana, Metrecubic ha participado en la Triatl\u00f3n de SGRAIL 100, una gran competici\u00f3n a nivel internacional.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/metrecubic.com\/es\/blog\/la-triatlon-de-sgrail-100\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Triatl\u00f3n de SGRAIL 100 - METRECUBIC\" \/>\n<meta property=\"og:description\" content=\"Este fin de semana, Metrecubic ha participado en la Triatl\u00f3n de SGRAIL 100, una gran competici\u00f3n a nivel internacional.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/metrecubic.com\/es\/blog\/la-triatlon-de-sgrail-100\/\" \/>\n<meta property=\"og:site_name\" content=\"METRECUBIC\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-10T09:06:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-01T11:34:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/metrecubic.com\/wp-content\/uploads\/La-Triatlon-de-SGRAIL-100.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1575\" \/>\n\t<meta property=\"og:image:height\" content=\"903\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"emfasi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"emfasi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/metrecubic.com\\\/es\\\/blog\\\/la-triatlon-de-sgrail-100\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/metrecubic.com\\\/es\\\/blog\\\/la-triatlon-de-sgrail-100\\\/\"},\"author\":{\"name\":\"emfasi\",\"@id\":\"https:\\\/\\\/metrecubic.com\\\/es\\\/#\\\/schema\\\/person\\\/a6ff476231cc7e78ec40fed152bcb241\"},\"headline\":\"La Triatl\u00f3n de SGRAIL 100\",\"datePublished\":\"2023-10-10T09:06:00+00:00\",\"dateModified\":\"2024-08-01T11:34:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/metrecubic.com\\\/es\\\/blog\\\/la-triatlon-de-sgrail-100\\\/\"},\"wordCount\":528,\"publisher\":{\"@id\":\"https:\\\/\\\/metrecubic.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/metrecubic.com\\\/es\\\/blog\\\/la-triatlon-de-sgrail-100\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/metrecubic.com\\\/wp-content\\\/uploads\\\/La-Triatlon-de-SGRAIL-100.webp\",\"articleSection\":[\"Metrecubic\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/metrecubic.com\\\/es\\\/blog\\\/la-triatlon-de-sgrail-100\\\/\",\"url\":\"https:\\\/\\\/metrecubic.com\\\/es\\\/blog\\\/la-triatlon-de-sgrail-100\\\/\",\"name\":\"La Triatl\u00f3n de SGRAIL 100 - METRECUBIC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/metrecubic.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/metrecubic.com\\\/es\\\/blog\\\/la-triatlon-de-sgrail-100\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/metrecubic.com\\\/es\\\/blog\\\/la-triatlon-de-sgrail-100\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/metrecubic.com\\\/wp-content\\\/uploads\\\/La-Triatlon-de-SGRAIL-100.webp\",\"datePublished\":\"2023-10-10T09:06:00+00:00\",\"dateModified\":\"2024-08-01T11:34:21+00:00\",\"description\":\"Este fin de semana, Metrecubic ha participado en la Triatl\u00f3n de SGRAIL 100, una gran competici\u00f3n a nivel internacional.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/metrecubic.com\\\/es\\\/blog\\\/la-triatlon-de-sgrail-100\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/metrecubic.com\\\/es\\\/blog\\\/la-triatlon-de-sgrail-100\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/metrecubic.com\\\/es\\\/blog\\\/la-triatlon-de-sgrail-100\\\/#primaryimage\",\"url\":\"https:\\\/\\\/metrecubic.com\\\/wp-content\\\/uploads\\\/La-Triatlon-de-SGRAIL-100.webp\",\"contentUrl\":\"https:\\\/\\\/metrecubic.com\\\/wp-content\\\/uploads\\\/La-Triatlon-de-SGRAIL-100.webp\",\"width\":1575,\"height\":903},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/metrecubic.com\\\/es\\\/blog\\\/la-triatlon-de-sgrail-100\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/metrecubic.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Triatl\u00f3n de SGRAIL 100\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/metrecubic.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/metrecubic.com\\\/es\\\/\",\"name\":\"METRECUBIC\",\"description\":\"Mudanzas y trasteros Sabadell y Girona\",\"publisher\":{\"@id\":\"https:\\\/\\\/metrecubic.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/metrecubic.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/metrecubic.com\\\/es\\\/#organization\",\"name\":\"METRECUBIC\",\"url\":\"https:\\\/\\\/metrecubic.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/metrecubic.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/metrecubic.com\\\/wp-content\\\/uploads\\\/logo-metrecubic.png\",\"contentUrl\":\"https:\\\/\\\/metrecubic.com\\\/wp-content\\\/uploads\\\/logo-metrecubic.png\",\"width\":159,\"height\":159,\"caption\":\"METRECUBIC\"},\"image\":{\"@id\":\"https:\\\/\\\/metrecubic.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/metrecubic.com\\\/es\\\/#\\\/schema\\\/person\\\/a6ff476231cc7e78ec40fed152bcb241\",\"name\":\"emfasi\",\"sameAs\":[\"https:\\\/\\\/metrecubic.com\"],\"url\":\"https:\\\/\\\/metrecubic.com\\\/es\\\/author\\\/emfasi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Triatl\u00f3n de SGRAIL 100 - METRECUBIC","description":"Este fin de semana, Metrecubic ha participado en la Triatl\u00f3n de SGRAIL 100, una gran competici\u00f3n a nivel internacional.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/metrecubic.com\/es\/blog\/la-triatlon-de-sgrail-100\/","og_locale":"es_ES","og_type":"article","og_title":"La Triatl\u00f3n de SGRAIL 100 - METRECUBIC","og_description":"Este fin de semana, Metrecubic ha participado en la Triatl\u00f3n de SGRAIL 100, una gran competici\u00f3n a nivel internacional.","og_url":"https:\/\/metrecubic.com\/es\/blog\/la-triatlon-de-sgrail-100\/","og_site_name":"METRECUBIC","article_published_time":"2023-10-10T09:06:00+00:00","article_modified_time":"2024-08-01T11:34:21+00:00","og_image":[{"width":1575,"height":903,"url":"https:\/\/metrecubic.com\/wp-content\/uploads\/La-Triatlon-de-SGRAIL-100.webp","type":"image\/webp"}],"author":"emfasi","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"emfasi","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/metrecubic.com\/es\/blog\/la-triatlon-de-sgrail-100\/#article","isPartOf":{"@id":"https:\/\/metrecubic.com\/es\/blog\/la-triatlon-de-sgrail-100\/"},"author":{"name":"emfasi","@id":"https:\/\/metrecubic.com\/es\/#\/schema\/person\/a6ff476231cc7e78ec40fed152bcb241"},"headline":"La Triatl\u00f3n de SGRAIL 100","datePublished":"2023-10-10T09:06:00+00:00","dateModified":"2024-08-01T11:34:21+00:00","mainEntityOfPage":{"@id":"https:\/\/metrecubic.com\/es\/blog\/la-triatlon-de-sgrail-100\/"},"wordCount":528,"publisher":{"@id":"https:\/\/metrecubic.com\/es\/#organization"},"image":{"@id":"https:\/\/metrecubic.com\/es\/blog\/la-triatlon-de-sgrail-100\/#primaryimage"},"thumbnailUrl":"https:\/\/metrecubic.com\/wp-content\/uploads\/La-Triatlon-de-SGRAIL-100.webp","articleSection":["Metrecubic"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/metrecubic.com\/es\/blog\/la-triatlon-de-sgrail-100\/","url":"https:\/\/metrecubic.com\/es\/blog\/la-triatlon-de-sgrail-100\/","name":"La Triatl\u00f3n de SGRAIL 100 - METRECUBIC","isPartOf":{"@id":"https:\/\/metrecubic.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/metrecubic.com\/es\/blog\/la-triatlon-de-sgrail-100\/#primaryimage"},"image":{"@id":"https:\/\/metrecubic.com\/es\/blog\/la-triatlon-de-sgrail-100\/#primaryimage"},"thumbnailUrl":"https:\/\/metrecubic.com\/wp-content\/uploads\/La-Triatlon-de-SGRAIL-100.webp","datePublished":"2023-10-10T09:06:00+00:00","dateModified":"2024-08-01T11:34:21+00:00","description":"Este fin de semana, Metrecubic ha participado en la Triatl\u00f3n de SGRAIL 100, una gran competici\u00f3n a nivel internacional.","breadcrumb":{"@id":"https:\/\/metrecubic.com\/es\/blog\/la-triatlon-de-sgrail-100\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/metrecubic.com\/es\/blog\/la-triatlon-de-sgrail-100\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/metrecubic.com\/es\/blog\/la-triatlon-de-sgrail-100\/#primaryimage","url":"https:\/\/metrecubic.com\/wp-content\/uploads\/La-Triatlon-de-SGRAIL-100.webp","contentUrl":"https:\/\/metrecubic.com\/wp-content\/uploads\/La-Triatlon-de-SGRAIL-100.webp","width":1575,"height":903},{"@type":"BreadcrumbList","@id":"https:\/\/metrecubic.com\/es\/blog\/la-triatlon-de-sgrail-100\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/metrecubic.com\/es\/"},{"@type":"ListItem","position":2,"name":"La Triatl\u00f3n de SGRAIL 100"}]},{"@type":"WebSite","@id":"https:\/\/metrecubic.com\/es\/#website","url":"https:\/\/metrecubic.com\/es\/","name":"METRECUBIC","description":"Mudanzas y trasteros Sabadell y Girona","publisher":{"@id":"https:\/\/metrecubic.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/metrecubic.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/metrecubic.com\/es\/#organization","name":"METRECUBIC","url":"https:\/\/metrecubic.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/metrecubic.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/metrecubic.com\/wp-content\/uploads\/logo-metrecubic.png","contentUrl":"https:\/\/metrecubic.com\/wp-content\/uploads\/logo-metrecubic.png","width":159,"height":159,"caption":"METRECUBIC"},"image":{"@id":"https:\/\/metrecubic.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/metrecubic.com\/es\/#\/schema\/person\/a6ff476231cc7e78ec40fed152bcb241","name":"emfasi","sameAs":["https:\/\/metrecubic.com"],"url":"https:\/\/metrecubic.com\/es\/author\/emfasi\/"}]}},"_links":{"self":[{"href":"https:\/\/metrecubic.com\/es\/wp-json\/wp\/v2\/posts\/1305","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/metrecubic.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/metrecubic.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/metrecubic.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/metrecubic.com\/es\/wp-json\/wp\/v2\/comments?post=1305"}],"version-history":[{"count":0,"href":"https:\/\/metrecubic.com\/es\/wp-json\/wp\/v2\/posts\/1305\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/metrecubic.com\/es\/wp-json\/wp\/v2\/media\/4231"}],"wp:attachment":[{"href":"https:\/\/metrecubic.com\/es\/wp-json\/wp\/v2\/media?parent=1305"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/metrecubic.com\/es\/wp-json\/wp\/v2\/categories?post=1305"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/metrecubic.com\/es\/wp-json\/wp\/v2\/tags?post=1305"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}