{"id":1742,"date":"2024-07-12T08:38:54","date_gmt":"2024-07-12T08:38:54","guid":{"rendered":"https:\/\/metrecubic.com\/?page_id=1742"},"modified":"2026-04-17T10:06:17","modified_gmt":"2026-04-17T10:06:17","slug":"alquiler-de-trasteros-en-girona","status":"publish","type":"page","link":"https:\/\/metrecubic.com\/es\/alquiler-de-trasteros-en-girona\/","title":{"rendered":"Alquiler de trasteros en Girona"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":4679,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-templates\/page-header-image-form.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-1742","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Alquiler de trasteros en Girona - METRECUBIC<\/title>\n<meta name=\"description\" content=\"Alquiler de trasteros en Girona centro, Sant Narc\u00eds y en el P.I Mas Xirgu. Tenemos el espacio que necesitas \u00a1Inf\u00f3rmate gratis! \u260e 972 40 59 69\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/metrecubic.com\/es\/alquiler-de-trasteros-en-girona\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alquiler de trasteros en Girona - METRECUBIC\" \/>\n<meta property=\"og:description\" content=\"Alquiler de trasteros en Girona centro, Sant Narc\u00eds y en el P.I Mas Xirgu. Tenemos el espacio que necesitas \u00a1Inf\u00f3rmate gratis! \u260e 972 40 59 69\" \/>\n<meta property=\"og:url\" content=\"https:\/\/metrecubic.com\/es\/alquiler-de-trasteros-en-girona\/\" \/>\n<meta property=\"og:site_name\" content=\"METRECUBIC\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-17T10:06:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/metrecubic.com\/wp-content\/uploads\/Cap-Trasteros-Girona-Mas-Xirgu.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"686\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/metrecubic.com\\\/es\\\/alquiler-de-trasteros-en-girona\\\/\",\"url\":\"https:\\\/\\\/metrecubic.com\\\/es\\\/alquiler-de-trasteros-en-girona\\\/\",\"name\":\"Alquiler de trasteros en Girona - METRECUBIC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/metrecubic.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/metrecubic.com\\\/es\\\/alquiler-de-trasteros-en-girona\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/metrecubic.com\\\/es\\\/alquiler-de-trasteros-en-girona\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/metrecubic.com\\\/wp-content\\\/uploads\\\/Cap-Trasteros-Girona-Mas-Xirgu.jpg\",\"datePublished\":\"2024-07-12T08:38:54+00:00\",\"dateModified\":\"2026-04-17T10:06:17+00:00\",\"description\":\"Alquiler de trasteros en Girona centro, Sant Narc\u00eds y en el P.I Mas Xirgu. Tenemos el espacio que necesitas \u00a1Inf\u00f3rmate gratis! \u260e 972 40 59 69\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/metrecubic.com\\\/es\\\/alquiler-de-trasteros-en-girona\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/metrecubic.com\\\/es\\\/alquiler-de-trasteros-en-girona\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/metrecubic.com\\\/es\\\/alquiler-de-trasteros-en-girona\\\/#primaryimage\",\"url\":\"https:\\\/\\\/metrecubic.com\\\/wp-content\\\/uploads\\\/Cap-Trasteros-Girona-Mas-Xirgu.jpg\",\"contentUrl\":\"https:\\\/\\\/metrecubic.com\\\/wp-content\\\/uploads\\\/Cap-Trasteros-Girona-Mas-Xirgu.jpg\",\"width\":1920,\"height\":686},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/metrecubic.com\\\/es\\\/alquiler-de-trasteros-en-girona\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/metrecubic.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Alquiler de trasteros en Girona\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/metrecubic.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/metrecubic.com\\\/es\\\/\",\"name\":\"METRECUBIC\",\"description\":\"Mudanzas y trasteros Sabadell y Girona\",\"publisher\":{\"@id\":\"https:\\\/\\\/metrecubic.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/metrecubic.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/metrecubic.com\\\/es\\\/#organization\",\"name\":\"METRECUBIC\",\"url\":\"https:\\\/\\\/metrecubic.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/metrecubic.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/metrecubic.com\\\/wp-content\\\/uploads\\\/logo-metrecubic.png\",\"contentUrl\":\"https:\\\/\\\/metrecubic.com\\\/wp-content\\\/uploads\\\/logo-metrecubic.png\",\"width\":159,\"height\":159,\"caption\":\"METRECUBIC\"},\"image\":{\"@id\":\"https:\\\/\\\/metrecubic.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Alquiler de trasteros en Girona - METRECUBIC","description":"Alquiler de trasteros en Girona centro, Sant Narc\u00eds y en el P.I Mas Xirgu. Tenemos el espacio que necesitas \u00a1Inf\u00f3rmate gratis! \u260e 972 40 59 69","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/metrecubic.com\/es\/alquiler-de-trasteros-en-girona\/","og_locale":"es_ES","og_type":"article","og_title":"Alquiler de trasteros en Girona - METRECUBIC","og_description":"Alquiler de trasteros en Girona centro, Sant Narc\u00eds y en el P.I Mas Xirgu. Tenemos el espacio que necesitas \u00a1Inf\u00f3rmate gratis! \u260e 972 40 59 69","og_url":"https:\/\/metrecubic.com\/es\/alquiler-de-trasteros-en-girona\/","og_site_name":"METRECUBIC","article_modified_time":"2026-04-17T10:06:17+00:00","og_image":[{"width":1920,"height":686,"url":"https:\/\/metrecubic.com\/wp-content\/uploads\/Cap-Trasteros-Girona-Mas-Xirgu.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/metrecubic.com\/es\/alquiler-de-trasteros-en-girona\/","url":"https:\/\/metrecubic.com\/es\/alquiler-de-trasteros-en-girona\/","name":"Alquiler de trasteros en Girona - METRECUBIC","isPartOf":{"@id":"https:\/\/metrecubic.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/metrecubic.com\/es\/alquiler-de-trasteros-en-girona\/#primaryimage"},"image":{"@id":"https:\/\/metrecubic.com\/es\/alquiler-de-trasteros-en-girona\/#primaryimage"},"thumbnailUrl":"https:\/\/metrecubic.com\/wp-content\/uploads\/Cap-Trasteros-Girona-Mas-Xirgu.jpg","datePublished":"2024-07-12T08:38:54+00:00","dateModified":"2026-04-17T10:06:17+00:00","description":"Alquiler de trasteros en Girona centro, Sant Narc\u00eds y en el P.I Mas Xirgu. Tenemos el espacio que necesitas \u00a1Inf\u00f3rmate gratis! \u260e 972 40 59 69","breadcrumb":{"@id":"https:\/\/metrecubic.com\/es\/alquiler-de-trasteros-en-girona\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/metrecubic.com\/es\/alquiler-de-trasteros-en-girona\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/metrecubic.com\/es\/alquiler-de-trasteros-en-girona\/#primaryimage","url":"https:\/\/metrecubic.com\/wp-content\/uploads\/Cap-Trasteros-Girona-Mas-Xirgu.jpg","contentUrl":"https:\/\/metrecubic.com\/wp-content\/uploads\/Cap-Trasteros-Girona-Mas-Xirgu.jpg","width":1920,"height":686},{"@type":"BreadcrumbList","@id":"https:\/\/metrecubic.com\/es\/alquiler-de-trasteros-en-girona\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/metrecubic.com\/es\/"},{"@type":"ListItem","position":2,"name":"Alquiler de trasteros en Girona"}]},{"@type":"WebSite","@id":"https:\/\/metrecubic.com\/es\/#website","url":"https:\/\/metrecubic.com\/es\/","name":"METRECUBIC","description":"Mudanzas y trasteros Sabadell y Girona","publisher":{"@id":"https:\/\/metrecubic.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/metrecubic.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/metrecubic.com\/es\/#organization","name":"METRECUBIC","url":"https:\/\/metrecubic.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/metrecubic.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/metrecubic.com\/wp-content\/uploads\/logo-metrecubic.png","contentUrl":"https:\/\/metrecubic.com\/wp-content\/uploads\/logo-metrecubic.png","width":159,"height":159,"caption":"METRECUBIC"},"image":{"@id":"https:\/\/metrecubic.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/metrecubic.com\/es\/wp-json\/wp\/v2\/pages\/1742","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/metrecubic.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/metrecubic.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/metrecubic.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/metrecubic.com\/es\/wp-json\/wp\/v2\/comments?post=1742"}],"version-history":[{"count":13,"href":"https:\/\/metrecubic.com\/es\/wp-json\/wp\/v2\/pages\/1742\/revisions"}],"predecessor-version":[{"id":9696,"href":"https:\/\/metrecubic.com\/es\/wp-json\/wp\/v2\/pages\/1742\/revisions\/9696"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/metrecubic.com\/es\/wp-json\/wp\/v2\/media\/4679"}],"wp:attachment":[{"href":"https:\/\/metrecubic.com\/es\/wp-json\/wp\/v2\/media?parent=1742"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}